{"id":45663,"date":"2026-05-12T18:00:00","date_gmt":"2026-05-12T16:00:00","guid":{"rendered":"https:\/\/gnews.cz\/?p=45663"},"modified":"2026-05-12T18:44:20","modified_gmt":"2026-05-12T16:44:20","slug":"cina-vydelava-na-exportu-produktu-souvisejicich-s-umelou-inteligenci-500-milionu-dolaru-za-hodinu","status":"publish","type":"post","link":"https:\/\/gnews.cz\/it\/neprehlednete\/cina-vydelava-na-exportu-produktu-souvisejicich-s-umelou-inteligenci-500-milionu-dolaru-za-hodinu\/","title":{"rendered":"La Cina guadagna 500 milioni di dollari al mese in esportazioni, compresi i prodotti legati all'AI"},"content":{"rendered":"<p><strong>NEW YORK - La Cina ha raggiunto il record di 359 miliardi di dollari di esportazioni ad aprile, pari a circa 500 milioni di dollari per il mese. Circa la met\u00e0 delle esportazioni era costituita da prodotti legati all'intelligenza artificiale. Questo secondo i calcoli di Bloomberg basati sui dati delle autorit\u00e0 doganali cinesi, della banca d'investimento Goldman Sachs e della societ\u00e0 di servizi finanziari giapponese Nomura Holdings.<\/strong><\/p>\n\n\n\n<p>Secondo i dati, il volume totale delle esportazioni \u00e8 aumentato del 14% rispetto all'anno precedente. Circa la met\u00e0 delle merci vendute all'estero \u00e8 costituita da apparecchiature per l'elaborazione dei dati, tra cui laptop, tablet e relativi componenti, nonch\u00e9 microchip. Nel frattempo, le esportazioni di microchip sono raddoppiate rispetto allo scorso anno. <strong>Bloomberg<\/strong> ha sottolineato che la crescita dei ricavi da esportazione \u00e8 stata favorita anche dalla carenza di semiconduttori a livello mondiale.<\/p>\n\n\n\n<p>Secondo la banca britannica<strong> Standard Chartered<\/strong> Lo scorso anno la Cina \u00e8 diventata il maggior fornitore mondiale di beni legati all'intelligenza artificiale.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>I dati dell'Amministrazione generale delle dogane della RPC mostrano che il commercio cinese con gli altri Paesi \u00e8 aumentato del 18,2% rispetto all'anno precedente, raggiungendo i 2,32 trilioni di dollari nel periodo gennaio-aprile. Le esportazioni nei primi quattro mesi dell'anno hanno raggiunto 1,33 trilioni di dollari, mentre le importazioni hanno totalizzato 989 miliardi di dollari. Nel solo mese di aprile, il fatturato commerciale della Cina con gli altri Paesi \u00e8 aumentato del 7,2% rispetto a marzo, raggiungendo i 634,06 miliardi di dollari.<\/p>\n<\/blockquote>\n\n\n\n<p>La Cina \u00e8 il maggior produttore mondiale e fornisce un'ampia gamma di prodotti ai mercati internazionali. \u00c8 inoltre uno dei principali partner commerciali per oltre <strong>150 paesi e regioni<\/strong>. Secondo le statistiche doganali, il volume del commercio estero cinese crescer\u00e0 del 3,8% nel 2024 e del 3,2% nel 2025, raggiungendo la cifra record di 6,35 trilioni di dollari.<\/p>\n\n\n\n<p><strong>gnews.cz - GH<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>NEW YORK - La Cina ha raggiunto il record di 359 miliardi di dollari di esportazioni in aprile, pari a circa 500 milioni di dollari per il mese. Circa...<\/p>","protected":false},"author":6,"featured_media":45664,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[7131,7144,4,3,2973],"tags":[4537,22,14247,4242,2489,14245,8488,4331,14246,17,614,41],"class_list":["post-45663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ai","category-ai-ekonomika","category-ekonomika","category-neprehlednete","category-zahranicni","tag-bloomberg","tag-cina","tag-cinsky-zahranicni-obchod","tag-export","tag-goldman-sachs","tag-mikrocipy","tag-nomura-holdings","tag-polovodice","tag-standard-chartered","tag-top","tag-umela-inteligence","tag-world"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/posts\/45663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/comments?post=45663"}],"version-history":[{"count":2,"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/posts\/45663\/revisions"}],"predecessor-version":[{"id":45681,"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/posts\/45663\/revisions\/45681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/media\/45664"}],"wp:attachment":[{"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/media?parent=45663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/categories?post=45663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gnews.cz\/it\/wp-json\/wp\/v2\/tags?post=45663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}